{"id":799503,"date":"2023-01-14T14:04:33","date_gmt":"2023-01-14T13:04:33","guid":{"rendered":"https:\/\/lauriersroses.jtni.nl\/reserver-un-emplacement\/"},"modified":"2026-06-11T15:34:44","modified_gmt":"2026-06-11T13:34:44","slug":"reserver-un-emplacement","status":"publish","type":"page","link":"https:\/\/info-lauriersroses.com\/fr\/reserver-un-emplacement\/","title":{"rendered":"R\u00e9server un emplacement"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.19.0&Prime; width=\u00a0\u00bb1080px\u00a0\u00bb width_tablet=\u00a0\u00bbauto\u00a0\u00bb width_phone=\u00a0\u00bbauto\u00a0\u00bb width_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.19.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>R\u00e9server un emplacement<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00a0\u00bbWidgets\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code admin_label=\u00a0\u00bbWidget du mois\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><ctv-availability data-product-type=\"pitch\" data-background-color=\"#FFFFFFFF\"><\/ctv-availability>[\/et_pb_code][et_pb_text admin_label=\u00a0\u00bbTitre produit pour calendirer\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>Emplacement pour une caravane ou une remorque pliante \/ tente + voiture \u2013 2 personnes<\/h2>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 522px; top: 6.975px;\">\n<div class=\"gtx-trans-icon\"> <\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00a0\u00bbWidget calendrier\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<ctv-product-search data-product-id=\"50414\"><\/ctv-product-search>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb3_5,2_5&Prime; admin_label=\u00a0\u00bbAncien formulaire\u00a0\u00bb module_class=\u00a0\u00bbd-none\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-988\"><form id=\"wpforms-form-988\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"988\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/799503\" data-token=\"643c79fb67b856ed8f59c3bbdefc8ec5\" data-token-time=\"1788341105\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#763f83\" data-scroll=\"1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 3<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:33.333333333333%;background-color:#763f83\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-988-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><\/div><div id=\"wpforms-988-field_39-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"39\"><h3 id=\"wpforms-988-field_39\">Emplacement<\/h3><\/div><div id=\"wpforms-988-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_1-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_1\">Date d&#039;arriv\u00e9e <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-988-field_1\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][1][date]\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-988-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_4\">Camping <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-988-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required=\"required\"><option value=\"Caravane\"  class=\"choice-1 depth-1\"  >Caravane<\/option><option value=\"Remorque pliante\"  class=\"choice-2 depth-1\"  >Remorque pliante<\/option><option value=\"Tente\"  class=\"choice-3 depth-1\"  >Tente<\/option><option value=\"Tente pop-up (max. 2 personnes)\"  class=\"choice-4 depth-1\"  >Tente pop-up (max. 2 personnes)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_2-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_2\">Date de d\u00e9part <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-988-field_2\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][2][date]\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-988-field_26-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"26\"><label class=\"wpforms-field-label\">\u00c9lectricit\u00e9 <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_26\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-988-field_26_1\" name=\"wpforms[fields][26]\" value=\"6A\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_26_1\">6A<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-988-field_26_2\" name=\"wpforms[fields][26]\" value=\"10A\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_26_2\">10A<\/label><\/li><\/ul><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_8-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"8\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_7-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_7\">Longueur (M) <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" step=\"any\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_6-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_6\">Largeur (M) <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" step=\"any\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_9-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"9\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_10-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_10\">Nombre de personnes <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" step=\"any\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_11-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_11\">dont jusqu&#039;\u00e0 2 ans<\/label><input type=\"number\" id=\"wpforms-988-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" step=\"any\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_13-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_13\">dont 3 \u00e0 6 ans<\/label><input type=\"number\" id=\"wpforms-988-field_13\" class=\"wpforms-field-medium\" name=\"wpforms[fields][13]\" step=\"any\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_41-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"41\"><label class=\"wpforms-field-label wpforms-label-hide\">R\u00e9frig\u00e9rateur<\/label><ul id=\"wpforms-988-field_41\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-988-field_41_1\" name=\"wpforms[fields][41][]\" value=\"Location de r\u00e9frig\u00e9rateur\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_41_1\">Location de r\u00e9frig\u00e9rateur<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_14-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_14\">Animaux domestiques<\/label><input type=\"number\" id=\"wpforms-988-field_14\" class=\"wpforms-field-medium\" name=\"wpforms[fields][14]\" step=\"any\" ><\/div><div id=\"wpforms-988-field_15-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_15\">V\u00e9hicule suppl\u00e9mentaire <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-988-field_15\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][15]\" required=\"required\"><option value=\"Non\"  class=\"choice-4 depth-1\"  >Non<\/option><option value=\"Voiture\"  class=\"choice-1 depth-1\"  >Voiture<\/option><option value=\"Moteur\"  class=\"choice-2 depth-1\"  >Moteur<\/option><option value=\"Bateau\"  class=\"choice-3 depth-1\"  >Bateau<\/option><\/select><\/div><div id=\"wpforms-988-field_27-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"27\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"1\" data-formid=\"988\" disabled>Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-988-field_16-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"16\"><h3 id=\"wpforms-988-field_16\">Vos donn\u00e9es<\/h3><\/div><div id=\"wpforms-988-field_17-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_17\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_17\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][17]\" required><\/div><div id=\"wpforms-988-field_18-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_18\">Adresse <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_18\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][18]\" required><\/div><div id=\"wpforms-988-field_19-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"19\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_30-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_30\">Code postal<\/label><input type=\"text\" id=\"wpforms-988-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_31-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_31\">Localisation <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_31\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][31]\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_21-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_21\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-988-field_21\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][21]\" aria-label=\"T\u00e9l\u00e9phone\" required><\/div><div id=\"wpforms-988-field_22-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_22\">Courriel : <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-988-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-988-field_23-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_23\">Commentaires<\/label><textarea id=\"wpforms-988-field_23\" class=\"wpforms-field-medium\" name=\"wpforms[fields][23]\" ><\/textarea><\/div><div id=\"wpforms-988-field_33-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"33\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"2\" data-formid=\"988\" disabled>Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"2\" data-formid=\"988\" disabled>Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3 last \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-988-field_34-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"34\"><h3 id=\"wpforms-988-field_34\">Arrhes<\/h3><\/div><div id=\"wpforms-988-field_37-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"37\"><div id=\"wpforms-988-field_37\" class=\"wpforms-field-large wpforms-field-row\"><p>Aujourd'hui vir\u00e9 sur le compte FR76 1009 6181 6200 0245 0720 142 au nom de Les  Lauriers Roses,  40% du montant du prix de  l'emplacement ou de la location, + 17,50 \u20ac de frais de r\u00e9servation.<\/p>\n<p>Je transf\u00e8re le montant restant apr\u00e8s r\u00e9ception de mon contrat de location \/solde facture de location au plus tard 2 semaines avant l'arriv\u00e9e pr\u00e9vue.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-988-field_38-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"38\"><label class=\"wpforms-field-label wpforms-label-hide\">D&#039;accord <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_38\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-988-field_38_1\" name=\"wpforms[fields][38][]\" value=\"Votre approbation\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_38_1\">Votre approbation<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_32-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"32\"><label class=\"wpforms-field-label\">Accord GDPR <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_32\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-988-field_32_1\" name=\"wpforms[fields][32][]\" value=\"J&#039;accepte que ce site Web stocke les donn\u00e9es que j&#039;ai soumises afin de pouvoir r\u00e9pondre \u00e0 mon message.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_32_1\">J'accepte que ce site Web stocke les donn\u00e9es que j'ai soumises afin de pouvoir r\u00e9pondre \u00e0 mon message.<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"988\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages\/799503\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-988\" class=\"wpforms-submit\" data-alt-text=\"Exp\u00e9dition...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/info-lauriersroses.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#ff000c\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb custom_margin=\u00a0\u00bb60px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Attention<\/h3>\n<p>Si vous utilisez <strong>hotmail.com, outlook.com, live.com ou msn.com <\/strong>, il est possible que notre r\u00e9ponse \u00e0 votre r\u00e9servation ou \u00e0 votre question aboutisse automatiquement dans votre dossier spam (en tant que message ind\u00e9sirable). Veuillez donc \u00e9galement v\u00e9rifier votre dossier de courrier ind\u00e9sirable si vous pensez que la r\u00e9ponse prend trop de temps ou utilisez une autre adresse \u00e9lectronique si n\u00e9cessaire.<\/p>\n<p>Nous nous excusons pour tout d\u00e9sagr\u00e9ment.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bb#000000&Prime; text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb1.5em\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#000000&Prime; header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#ff000c\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>AVG\/GDPR<\/h3>\n<p>Les donn\u00e9es recueillies dans ce formulaire sont enregistr\u00e9es par la SARL Camping Les Lauriers Roses dans un fichier destin\u00e9 \u00e0 la gestion de la client\u00e8le. Ces donn\u00e9es sont conserv\u00e9es pendant 1 an et sont destin\u00e9es au service marketing et commercial.<\/p>\n<p>Conform\u00e9ment \u00e0 la loi \u00ab\u00a0Informatique et Libert\u00e9s\u00a0\u00bb, vous disposez d&rsquo;un droit d&rsquo;acc\u00e8s \u00e0 vos donn\u00e9es. Pour supprimer ou modifier vos donn\u00e9es, veuillez contacter : M. Van Bemmel Andre (Directeur)<br \/><a href=\"mailto:camping@info-lauriersroses.com\">camping@info-lauriersroses.com<\/a><\/p>\n<p>Vous pouvez \u00e9galement vous opposer au traitement des donn\u00e9es vous concernant pour des raisons l\u00e9gitimes.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9server un emplacementEmplacement pour une caravane ou une remorque pliante \/ tente + voiture \u2013 2 personnes <div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-988\"><form id=\"wpforms-form-988\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"988\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/fr\/wp-json\/wp\/v2\/pages\/799503\" data-token=\"643c79fb67b856ed8f59c3bbdefc8ec5\" data-token-time=\"1788341105\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-page-indicator progress\" data-indicator=\"progress\" data-indicator-color=\"#763f83\" data-scroll=\"1\"><span class=\"wpforms-page-indicator-page-title\" ><\/span><span class=\"wpforms-page-indicator-page-title-sep\" style=\"display:none;\"> - <\/span><span class=\"wpforms-page-indicator-steps\">Step <span class=\"wpforms-page-indicator-steps-current\">1<\/span> of 3<\/span><div class=\"wpforms-page-indicator-page-progress-wrap\"><div class=\"wpforms-page-indicator-page-progress\" style=\"width:33.333333333333%;background-color:#763f83\"><\/div><\/div><\/div><div class=\"wpforms-field-container\"><div class=\"wpforms-page wpforms-page-1 \" data-page=\"1\"><div id=\"wpforms-988-field_28-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"28\"><\/div><div id=\"wpforms-988-field_39-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"39\"><h3 id=\"wpforms-988-field_39\">Emplacement<\/h3><\/div><div id=\"wpforms-988-field_3-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"3\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_1-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_1\">Date d&#039;arriv\u00e9e <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-988-field_1\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][1][date]\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-988-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_4\">Camping <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-988-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" required=\"required\"><option value=\"Caravane\"  class=\"choice-1 depth-1\"  >Caravane<\/option><option value=\"Remorque pliante\"  class=\"choice-2 depth-1\"  >Remorque pliante<\/option><option value=\"Tente\"  class=\"choice-3 depth-1\"  >Tente<\/option><option value=\"Tente pop-up (max. 2 personnes)\"  class=\"choice-4 depth-1\"  >Tente pop-up (max. 2 personnes)<\/option><\/select><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_2-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_2\">Date de d\u00e9part <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-988-field_2\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-medium\" data-date-format=\"d\/m\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][2][date]\" required><a title=\"Effacer la date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Effacer la date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-988-field_26-container\" class=\"wpforms-field wpforms-field-radio\" data-field-id=\"26\"><label class=\"wpforms-field-label\">\u00c9lectricit\u00e9 <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_26\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"wpforms-988-field_26_1\" name=\"wpforms[fields][26]\" value=\"6A\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_26_1\">6A<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"wpforms-988-field_26_2\" name=\"wpforms[fields][26]\" value=\"10A\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_26_2\">10A<\/label><\/li><\/ul><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_8-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"8\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_7-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_7\">Longueur (M) <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" step=\"any\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_6-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_6\">Largeur (M) <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" step=\"any\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_9-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"9\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-33-33-33\"><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_10-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_10\">Nombre de personnes <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"number\" id=\"wpforms-988-field_10\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][10]\" step=\"any\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_11-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_11\">dont jusqu&#039;\u00e0 2 ans<\/label><input type=\"number\" id=\"wpforms-988-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" step=\"any\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-33\" ><div id=\"wpforms-988-field_13-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_13\">dont 3 \u00e0 6 ans<\/label><input type=\"number\" id=\"wpforms-988-field_13\" class=\"wpforms-field-medium\" name=\"wpforms[fields][13]\" step=\"any\" ><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_41-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"41\"><label class=\"wpforms-field-label wpforms-label-hide\">R\u00e9frig\u00e9rateur<\/label><ul id=\"wpforms-988-field_41\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-988-field_41_1\" name=\"wpforms[fields][41][]\" value=\"Location de r\u00e9frig\u00e9rateur\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_41_1\">Location de r\u00e9frig\u00e9rateur<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_14-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"14\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_14\">Animaux domestiques<\/label><input type=\"number\" id=\"wpforms-988-field_14\" class=\"wpforms-field-medium\" name=\"wpforms[fields][14]\" step=\"any\" ><\/div><div id=\"wpforms-988-field_15-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-classic\" data-field-id=\"15\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_15\">V\u00e9hicule suppl\u00e9mentaire <span class=\"wpforms-required-label\">*<\/span><\/label><select id=\"wpforms-988-field_15\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][15]\" required=\"required\"><option value=\"Non\"  class=\"choice-4 depth-1\"  >Non<\/option><option value=\"Voiture\"  class=\"choice-1 depth-1\"  >Voiture<\/option><option value=\"Moteur\"  class=\"choice-2 depth-1\"  >Moteur<\/option><option value=\"Bateau\"  class=\"choice-3 depth-1\"  >Bateau<\/option><\/select><\/div><div id=\"wpforms-988-field_27-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"27\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"1\" data-formid=\"988\" disabled>Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-2  \" data-page=\"2\" style=\"display:none;\"><div id=\"wpforms-988-field_16-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"16\"><h3 id=\"wpforms-988-field_16\">Vos donn\u00e9es<\/h3><\/div><div id=\"wpforms-988-field_17-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"17\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_17\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_17\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][17]\" required><\/div><div id=\"wpforms-988-field_18-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"18\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_18\">Adresse <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_18\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][18]\" required><\/div><div id=\"wpforms-988-field_19-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"19\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_30-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"30\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_30\">Code postal<\/label><input type=\"text\" id=\"wpforms-988-field_30\" class=\"wpforms-field-medium\" name=\"wpforms[fields][30]\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-988-field_31-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"31\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_31\">Localisation <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-988-field_31\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][31]\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-988-field_21-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"21\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_21\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"tel\" id=\"wpforms-988-field_21\" class=\"wpforms-field-medium wpforms-field-required wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][21]\" aria-label=\"T\u00e9l\u00e9phone\" required><\/div><div id=\"wpforms-988-field_22-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_22\">Courriel : <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-988-field_22\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][22]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-988-field_23-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"23\"><label class=\"wpforms-field-label\" for=\"wpforms-988-field_23\">Commentaires<\/label><textarea id=\"wpforms-988-field_23\" class=\"wpforms-field-medium\" name=\"wpforms[fields][23]\" ><\/textarea><\/div><div id=\"wpforms-988-field_33-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"33\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><button class=\"wpforms-page-button wpforms-page-prev\" data-action=\"prev\" data-page=\"2\" data-formid=\"988\" disabled>Pr\u00e9c\u00e9dent<\/button><button class=\"wpforms-page-button wpforms-page-next\" data-action=\"next\" data-page=\"2\" data-formid=\"988\" disabled>Suivant<\/button><\/div><\/div><\/div><div class=\"wpforms-page wpforms-page-3 last \" data-page=\"3\" style=\"display:none;\"><div id=\"wpforms-988-field_34-container\" class=\"wpforms-field wpforms-field-divider\" data-field-id=\"34\"><h3 id=\"wpforms-988-field_34\">Arrhes<\/h3><\/div><div id=\"wpforms-988-field_37-container\" class=\"wpforms-field wpforms-field-content\" data-field-id=\"37\"><div id=\"wpforms-988-field_37\" class=\"wpforms-field-large wpforms-field-row\"><p>Aujourd'hui vir\u00e9 sur le compte FR76 1009 6181 6200 0245 0720 142 au nom de Les  Lauriers Roses,  40% du montant du prix de  l'emplacement ou de la location, + 17,50 \u20ac de frais de r\u00e9servation.<\/p>\n<p>Je transf\u00e8re le montant restant apr\u00e8s r\u00e9ception de mon contrat de location \/solde facture de location au plus tard 2 semaines avant l'arriv\u00e9e pr\u00e9vue.<\/p>\n<div class=\"wpforms-field-content-display-frontend-clear\"><\/div><\/div><\/div><div id=\"wpforms-988-field_38-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"38\"><label class=\"wpforms-field-label wpforms-label-hide\">D&#039;accord <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_38\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-988-field_38_1\" name=\"wpforms[fields][38][]\" value=\"Votre approbation\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_38_1\">Votre approbation<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_32-container\" class=\"wpforms-field wpforms-field-gdpr-checkbox\" data-field-id=\"32\"><label class=\"wpforms-field-label\">Accord GDPR <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-988-field_32\" class=\"wpforms-field-required\"><li class=\"choice-1\"><input type=\"checkbox\" id=\"wpforms-988-field_32_1\" name=\"wpforms[fields][32][]\" value=\"J&#039;accepte que ce site Web stocke les donn\u00e9es que j&#039;ai soumises afin de pouvoir r\u00e9pondre \u00e0 mon message.\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-988-field_32_1\">J'accepte que ce site Web stocke les donn\u00e9es que j'ai soumises afin de pouvoir r\u00e9pondre \u00e0 mon message.<\/label><\/li><\/ul><\/div><div id=\"wpforms-988-field_29-container\" class=\"wpforms-field wpforms-field-pagebreak\" data-field-id=\"29\"><div class=\"wpforms-clear wpforms-pagebreak-left\"><\/div><\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" style=\"display:none;\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"988\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages\/799503\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-988\" class=\"wpforms-submit\" data-alt-text=\"Exp\u00e9dition...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/info-lauriersroses.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->Attention Si vous utilisez hotmail.com, outlook.com, live.com ou msn.com , il est possible que notre r\u00e9ponse \u00e0 votre r\u00e9servation ou \u00e0 votre question aboutisse automatiquement dans votre dossier spam (en tant que message ind\u00e9sirable). Veuillez donc \u00e9galement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-799503","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages\/799503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/comments?post=799503"}],"version-history":[{"count":15,"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages\/799503\/revisions"}],"predecessor-version":[{"id":802612,"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/pages\/799503\/revisions\/802612"}],"wp:attachment":[{"href":"https:\/\/info-lauriersroses.com\/fr\/wp-json\/wp\/v2\/media?parent=799503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}